{"id":8719,"date":"2014-09-10T05:24:14","date_gmt":"2014-09-10T12:24:14","guid":{"rendered":"http:\/\/www.consensus911.org\/?page_id=8719"},"modified":"2021-09-26T09:36:21","modified_gmt":"2021-09-26T16:36:21","slug":"point-mc-9-fr","status":"publish","type":"page","link":"https:\/\/www.consensus911.org\/fr\/point-mc-9-fr\/","title":{"rendered":"Point MC-9 (Fr)"},"content":{"rendered":"<h4 class=\"c9h4\">Point MC-9&nbsp;: Les activit\u00e9s du G\u00e9n\u00e9ral Ralph Eberhart<br \/><span style=\"color: #ffffff\">Point MC-9&nbsp;:<\/span> pendant les attentats du 11-Septembre<\/h4>\n<div class=\"c9text-fr\">\n<p class=\"c9np\"><a href=\"https:\/\/www.consensus911.org\/fr\/point-mc-8-fr\/\">&lt;&lt; Point pr\u00e9c\u00e9dent<\/a>, <a href=\"https:\/\/www.consensus911.org\/fr\/point-mc-10-fr\/\">Point suivant &gt;&gt;<\/a><\/p>\n<div class=\"c9hdr\"><a name=\"INTRO\"><\/a>Introduction<\/div>\n<div style=\"padding-left: 30px\">\nLe NORAD est l\u2019agence am\u00e9ricano-canadienne en charge de d\u00e9fendre l\u2019espace a\u00e9rien de l\u2019Am\u00e9rique du Nord. Ses proc\u00e9dures op\u00e9rationnelles standard \u2013 pour intercepter les avions lorsqu\u2019ils d\u00e9vient de leur trajectoire, \u00e9teignent leur transpondeur ou perdent le contact radio \u2013 n\u2019ont pas \u00e9t\u00e9 suivies le 11-Septembre.<\/p>\n<p>En tant que commandant en chef du NORAD le 11-Septembre, le g\u00e9n\u00e9ral Ralph E. \u00ab&nbsp;Ed&nbsp;\u00bb Eberhart est donc responsable de toutes les d\u00e9faillances du NORAD le 11 septembre 2001 \u2013 et en particulier, de l\u2019\u00e9chec \u00e0 intercepter les avions de ligne avant qu\u2019ils ne frappent les Tours Jumelles et le Pentagone. Le 4e avion, le vol UA&nbsp;93, qui \u00e9tait semble-t-il en train de se diriger vers la capitale, pourrait avoir \u00e9t\u00e9 abattu par le NORAD, mais ce dernier l\u2019a toujours ni\u00e9. Par cons\u00e9quent, officiellement ce sont quatre avions que le NORAD n\u2019a pas r\u00e9ussi \u00e0 intercepter ce jour-l\u00e0.<\/p>\n<p>Pourtant, malgr\u00e9 les d\u00e9faillances d\u00e9sastreuses du NORAD sous le commandement du g\u00e9n\u00e9ral Eberhart, celui-ci n\u2019a jamais \u00e9t\u00e9 tenu pour responsable ni m\u00eame critiqu\u00e9. Pire, il a re\u00e7u une promotion peu apr\u00e8s le 11\/9 et on l\u2019a qualifi\u00e9 par la suite de \u00ab&nbsp;h\u00e9ros du 11\/9&nbsp;\u00bb.&nbsp;<a name=\"R_1\" href=\"#N_1\">[1]<\/a><\/p>\n<p>Contrairement \u00e0 d\u2019autres comme le G\u00e9n\u00e9ral Richard Myers ou le G\u00e9n\u00e9ral Shelton, Eberhart n\u2019a pas r\u00e9dig\u00e9 de compte-rendu de ses faits et gestes le 11\/9. Et il n\u2019a \u00e9t\u00e9 interrog\u00e9 que de fa\u00e7on tr\u00e8s parcellaire par la Commission sur le 11\/9, si bien que nous n\u2019avons que tr\u00e8s peu d\u2019informations sur ses actions ce jour-l\u00e0. Mais suffisamment de choses ont \u00e9t\u00e9 dites ou rapport\u00e9es par de hauts responsables et par les m\u00e9dias pour nous permettre d\u2019avoir une bonne id\u00e9e de ce qu\u2019Eberhart a officiellement fait le 11-Septembre.\n<\/p><\/div>\n<div class=\"c9hdr\"><a name=\"OFFICIAL\"><\/a>La version officielle<\/div>\n<ul style=\"padding-left: 30px\">\n<li>\u00ab&nbsp;Le matin du 11-Septembre, le G\u00e9n\u00e9ral Eberhart \u00e9tait \u00e0 son bureau au quartier g\u00e9n\u00e9ral \u2013 situ\u00e9 \u00e0 environ 30 minutes de Cheyenne Mountain, o\u00f9 se trouve le Centre op\u00e9rationnel (abr\u00e9g\u00e9 en CMOC, pour Cheyenne Mountain Operation Center)\u00bb&nbsp;<a name=\"R_2\" href=\"#N_2\">[2]<\/a><\/li>\n<li>\u00ab&nbsp;Eberhart a re\u00e7u un appel \u00e0 6 h 45 MDT (<i>Mountain Daylight Time<\/i>, soit 8 h 45 EDT) du directeur du CMOC l\u2019informant de la pr\u00e9sence d\u2019un appareil suspect\u00e9 de d\u00e9tournement sur la c\u00f4te Est. On lui a pr\u00e9cis\u00e9 qu\u2019il ne s\u2019agissait pas d\u2019un exercice. Il s\u2019est rendu \u00e0 son bureau et a regard\u00e9 le reportage de CNN montrant l\u2019explosion au World Trade Center.&nbsp;\u00bb&nbsp;<a name=\"R_3\" href=\"#N_3\">[3]<\/a><\/li>\n<li>Eberhart a eu l\u2019impression qu\u2019il r\u00e9gnait \u00ab&nbsp;une grande confusion dans le syst\u00e8me&nbsp;\u00bb \u00e0 ce moment-l\u00e0. (C\u2019est \u00e9galement ce qu\u2019a dit le g\u00e9n\u00e9ral de corps d&rsquo;arm\u00e9e canadien Rick Findley, directeur du personnel de combat au CMOC, lequel a d\u00e9clar\u00e9 plus tard \u00e0 la Commission sur le 11\/9 qu\u2019apr\u00e8s la 2e attaque contre les Tours Jumelles, il r\u00e9gnait une \u00ab&nbsp;confusion sur le nombre et l\u2019identit\u00e9 des avions d\u00e9tourn\u00e9s.&nbsp;\u00bb&nbsp;<a name=\"R_4\" href=\"#N_4\">[4]<\/a>) Lorsqu\u2019Eberhart prit connaissance de la 2e frappe contre le WTC, il devint \u00e9vident pour lui qu\u2019une \u00ab&nbsp;attaque terroriste coordonn\u00e9e&nbsp;\u00bb \u00e9tait en cours.&nbsp;<a name=\"R_5\" href=\"#N_5\">[5]<\/a><\/li>\n<li>Eberhart tenta de contacter le Chef d\u2019\u00c9tat-major interarmes, le g\u00e9n\u00e9ral Henry Shelton, mais n\u2019y parvint pas, puisque Shelton \u00e9tait en route vers l\u2019Europe o\u00f9 il devait assister \u00e0 une r\u00e9union de l\u2019OTAN.&nbsp;<a name=\"R_6\" href=\"#N_6\">[6]<\/a><\/li>\n<li>Eberhart a ensuite contact\u00e9 l\u2019adjoint du Chef d\u2019\u00c9tat-major interarmes, le g\u00e9n\u00e9ral Richard Myers, qui se trouvait \u00e0 Capitole Hill en compagnie du S\u00e9nateur Max Cleland. Eberhart a appel\u00e9 Myers entre 9 h 03 et 9 h 30 du matin, c\u2019est-\u00e0-dire avant la frappe contre le Pentagone, qui est survenue vers 9 h 37.&nbsp;<a name=\"R_7\" href=\"#N_7\">[7]<\/a><\/li>\n<li>Eberhart a inform\u00e9 Myers de la situation de crise en cours, lui expliquant que les Tours Jumelles avaient \u00e9t\u00e9 frapp\u00e9es, que le NORAD allait r\u00e9agir en lan\u00e7ant des avions de chasse, et qu\u2019il travaillait conjointement avec la FAA pour faire atterrir tous les avions non militaires circulant dans le ciel des \u00c9tats-Unis.&nbsp;<a name=\"R_8\" href=\"#N_8\">[8]<\/a><\/li>\n<li>D\u2019apr\u00e8s Myers, Eberhart lui a dit qu\u2019il y avait \u00ab&nbsp;de nombreux signaux de d\u00e9tournements dans le syst\u00e8me,&nbsp;\u00bb&nbsp;<a name=\"R_9\" href=\"#N_9\">[9]<\/a> ce qui signifie, selon Myers, \u00ab&nbsp;que les transpondeurs des avions envoyaient leur signaux au sol, et qu\u2019ils disaient &#8230; \u2018nous avons \u00e9t\u00e9 d\u00e9tourn\u00e9s\u2019.&nbsp;\u00bb&nbsp;<a name=\"R_10\" href=\"#N_10\">[10]<\/a><\/li>\n<li>Eberhart a ensuite d\u00e9clar\u00e9 qu\u2019il allait rester dans le B\u00e2timent 1 de la base Peterson de l\u2019US Air Force \u2013 le Q.G du commandement de l\u2019Air Force (\u00e9galement sous les ordres d\u2019Eberhart) \u2013, car expliqua-t-il, \u00ab&nbsp;il ne voulait pas perdre la communication.&nbsp;\u00bb Pourtant, il a alors d\u00e9cid\u00e9 de se rendre en voiture au Centre des Op\u00e9rations de Cheyenne Mountain, \u00ab&nbsp;aux environs de 9 h 30&nbsp;\u00bb EDT (ou 7 h 30 MDT), c\u2019est-\u00e0-dire peu de temps apr\u00e8s sa conversation avec Myers. Interrog\u00e9 sur les raisons qui l\u2019avaient pouss\u00e9 \u00e0 entreprendre ce voyage en voiture au beau milieu de la crise, Eberhart a expliqu\u00e9 que les choses \u00ab&nbsp;s\u2019\u00e9taient calm\u00e9es&nbsp;\u00bb et que le Centre des Op\u00e9rations \u00ab&nbsp;disposait de moyens de communication que Peterson n\u2019avait pas.&nbsp;\u00bb&nbsp;<a name=\"R_11\" href=\"#N_11\">[11]<\/a><\/li>\n<li>Bien que selon la Commission sur le 11\/9, la dur\u00e9e moyenne de ce trajet de 12 miles (20 km) soit d\u2019environ 30 minutes, il en a fallu 45 \u00e0 Eberhart pour parvenir \u00e0 destination. Le <i>Washington Post<\/i> expliquera plus tard que le trajet \u00ab&nbsp;peut prendre plus de temps en cas d\u2019embouteillage.&nbsp;\u00bb&nbsp;<a name=\"R_12\" href=\"#N_12\">[12]<\/a> Et comme on l\u2019a appris par la suite, pendant tout ce trajet, Eberhart \u00ab&nbsp;n\u2019a pas pu recevoir les appels, alors que tous les hauts grad\u00e9s \u00e9taient en attente des directives,&nbsp;\u00bb&nbsp;<a name=\"R_13\" href=\"#N_13\">[13]<\/a> ou du moins il n\u2019a pas pu rester en communication avec eux&nbsp;: \u00ab&nbsp;Il a loup\u00e9 un appel t\u00e9l\u00e9phonique du vice-pr\u00e9sident Dick Cheney.&nbsp;\u00bb&nbsp;<a name=\"R_14\" href=\"#N_14\">[14]<\/a><\/li>\n<li>A 9 h 49, pendant la t\u00e9l\u00e9conf\u00e9rence au Pentagone sur les menaces a\u00e9riennes, Eberhart a ordonn\u00e9 \u00ab&nbsp;\u00e0 tous les appareils de regagner leur poste de combat avec le plein de munitions.&nbsp;\u00bb&nbsp;<a name=\"R_15\" href=\"#N_15\">[15]<\/a><\/li>\n<li>La Commission sur le 11\/9 a demand\u00e9 \u00e0 Eberhart les raisons pour lesquelles, une fois qu\u2019il eut r\u00e9alis\u00e9 qu\u2019il s\u2019agissait d\u2019une attaque terroriste coordonn\u00e9e contre le pays, il n\u2019a pas d\u00e9clench\u00e9 le plan appel\u00e9 SCATANA (<a href=\"https:\/\/en.wikipedia.org\/wiki\/Security_Control_of_Air_Traffic_and_Air_Navigation_Aids\">Security Control of Air Traffic and Air Navigation Aids<\/a>), qui aurait nettoy\u00e9 le ciel de tous les avions non militaires, de fa\u00e7on \u00e0 ce que l\u2019US Air Space puisse prendre le contr\u00f4le total de l\u2019espace a\u00e9rien nord-am\u00e9ricain. Eberhart a expliqu\u00e9 qu\u2019avec les radars dont il disposait, le NORAD n\u2019aurait pas \u00e9t\u00e9 en mesure de prendre \u00ab&nbsp;le contr\u00f4le de l\u2019espace a\u00e9rien ce jour-l\u00e0,&nbsp;\u00bb et que donc, si SCATANA avait \u00e9t\u00e9 d\u00e9clench\u00e9 \u00e0 l\u2019improviste, cela aurait cr\u00e9\u00e9 encore plus de probl\u00e8mes. En r\u00e9ponse \u00e0 ceux qui, au sein du NORAD, lui avaient demand\u00e9 de lancer ce plan, Eberhart avait r\u00e9torqu\u00e9&nbsp;: \u00ab&nbsp;Je vais d\u00e9clencher SCATANA une fois que vous aurez modifi\u00e9 SCATANA &#8230; pour qu\u2019il n\u2019empire pas encore plus la situation.&nbsp;\u00bb Deux heures apr\u00e8s la frappe du deuxi\u00e8me avion contre le WTC, Eberhart a pu lancer le plan SCATANA modifi\u00e9.&nbsp;<a name=\"R_16\" href=\"#N_16\">[16]<\/a><\/li>\n<\/ul>\n<p><a name=\"EVIDENCE\"><\/a><\/p>\n<div class=\"c9hdr\">Les \u00e9l\u00e9ments les plus probants<\/div>\n<div style=\"padding-left: 30px\">\n<p>L\u2019examen des faits montre qu\u2019Eberhart, plut\u00f4t que de passer pour un \u00ab&nbsp;h\u00e9ros du 11\/9&nbsp;\u00bb devrait plut\u00f4t \u00eatre consid\u00e9r\u00e9 comme l\u2019inverse. On peut distinguer deux cat\u00e9gories d\u2019\u00e9l\u00e9ments factuels&nbsp;:<\/p>\n<ol style=\"padding-left: 30px\">\n<li>Eberhart a fait plusieurs d\u00e9clarations peu plausibles, voire contradictoires<\/li>\n<li>Par ses actions ou son absence d\u2019action, Eberhart est \u00e0 l\u2019origine de certains retards et d\u00e9lais de r\u00e9action<\/li>\n<\/ol>\n<p><b>1. Eberhart a fait plusieurs d\u00e9clarations peu plausibles, et contradictoires<\/b><\/p>\n<div style=\"padding-left: 30px\">\nLe r\u00e9cit officiel des faits et gestes d\u2019Eberhart contient les \u00e9l\u00e9ments suivants, dans leur ordre d\u2019apparition tel que list\u00e9 ci-dessus&nbsp;:<\/p>\n<ul style=\"padding-left: 30px\">\n<li>Eberhart a d\u00e9clar\u00e9 qu\u2019il avait commenc\u00e9 par essayer de contacter le G\u00e9n\u00e9ral Shelton, et avait appris que ce dernier \u00e9tait en route pour l\u2019Europe. Mais \u00e9tant donn\u00e9 que le voyage de Shelton avait \u00e9t\u00e9 planifi\u00e9 de longue date, le fait qu\u2019Eberhart ne savait pas que son sup\u00e9rieur imm\u00e9diat (le chef d\u2019\u00e9tat-major interarmes) serait absent \u00e0 ce moment-l\u00e0 n\u2019est pas cr\u00e9dible.<\/li>\n<li>Eberhart a dit avoir appel\u00e9 le G\u00e9n\u00e9ral Myers alors que ce dernier \u00e9tait \u00e0 Capitole Hill \u2013 ce qui est faux, comme document\u00e9 dans le Point de Consensus concernant Myers.&nbsp;<a name=\"R_17\" href=\"#N_17\">[17]<\/a><\/li>\n<li>Bien qu\u2019Eberhart ait expliqu\u00e9 que les avions d\u00e9tourn\u00e9s avaient utilis\u00e9 le code d\u2019alerte de d\u00e9tournement (Hijack Code) et \u00e9taient en communication avec le sol, le fait qu\u2019aucun des huit pilotes n\u2019ait d\u00e9clench\u00e9 ce code d\u2019alerte constitue l\u2019un des probl\u00e8mes majeurs de la version officielle.&nbsp;<a name=\"R_18\" href=\"#N_18\">[18]<\/a><\/li>\n<li>M\u00eame si Eberhart a justifi\u00e9 sa d\u00e9cision de se rendre en voiture au Centre des Op\u00e9rations en disant que les choses \u00ab&nbsp;s\u2019\u00e9taient calm\u00e9es,&nbsp;\u00bb les deux avions d\u00e9tourn\u00e9s \u00e9taient toujours en l\u2019air (et il \u00e9tait au courant, vu sa d\u00e9claration \u00e0 propos des codes d\u2019alerte d\u00e9tournement).<\/li>\n<li>Si toutefois il avait de bonnes raisons de se rendre au Centre des op\u00e9rations, il aurait pu y aller tr\u00e8s rapidement en h\u00e9licopt\u00e8re, plut\u00f4t que de perdre 45 minutes \u00e0 parcourir cette distance en voiture).&nbsp;<a name=\"R_19\" href=\"#N_19\">[19]<\/a><\/li>\n<li>Bien qu\u2019\u00c9berhart ait affirm\u00e9 ne pas avoir pu t\u00e9l\u00e9phoner \u00e0 l\u2019aide de son appareil cellulaire pendant ce voyage, il aurait ordonn\u00e9 \u00e0 9 h 49 (c\u2019est-\u00e0-dire 7&nbsp;:49 heure locale) \u00e0 tous les pilotes de chasse de regagner leur poste de combat, lors d\u2019une conf\u00e9rence sur la menace a\u00e9rienne.&nbsp;<a name=\"R_20\" href=\"#N_20\">[20]<\/a><\/li>\n<li>M\u00eame si \u00ab&nbsp;regagner son poste de combat&nbsp;\u00bb semble indiquer une action, cela signifie que les pilotes doivent attendre dans leurs jets tous moteurs \u00e9teints ; ils n\u2019\u00e9taient donc pas pr\u00eats \u00e0 d\u00e9coller imm\u00e9diatement.&nbsp;<a name=\"R_21\" href=\"#N_21\">[21]<\/a><\/li>\n<li>L\u2019affirmation d\u2019Eberhart selon laquelle il n\u2019a pas pu d\u00e9clencher imm\u00e9diatement le plan SCATANA pour ne pas risquer d\u2019empirer encore la situation n\u2019est tout simplement pas cr\u00e9dible, \u00e9tant donn\u00e9 que SCATANA est une proc\u00e9dure mise en place pour les cas d\u2019urgence, et que le SCATANA modifi\u00e9 avait tr\u00e8s certainement d\u00e9j\u00e0 \u00e9t\u00e9 mis au point, vu tous les exercices conduits par le NORAD durant cette p\u00e9riode, dont l\u2019un simulait le crash d\u2019un avion contre un gratte-ciel \u00e0 Manhattan. De m\u00eame, les officiers du NORAD qui ont conseill\u00e9 \u00e0 EBERHART de lancer le plan SCATANA n\u2019y voyaient quant \u00e0 eux aucun probl\u00e8me.<\/li>\n<\/ul>\n<p>Par cons\u00e9quent, la version officielle concernant Eberhart contient des impr\u00e9cisions, des affirmations p\u00e9remptoires et un ensemble d\u2019actions et d\u2019omissions qui ont g\u00e9n\u00e9r\u00e9 des retards dans l\u2019interception des avions d\u00e9tourn\u00e9s.\n<\/p><\/div>\n<p><b>2. Par ses actions ou son absence d\u2019action, Eberhart est \u00e0 l\u2019origine de certains retards et d\u00e9lais de r\u00e9action<\/b><\/p>\n<div style=\"padding-left: 30px\">\nIl existe d\u2019autres anomalies au sujet des faits et gestes, et aussi des d\u00e9clarations d\u2019Eberhart.<\/p>\n<ul style=\"padding-left: 30px\">\n<li>Le NORAD poss\u00e8de une proc\u00e9dure standard d\u2019interception au cas o\u00f9 un avion perd le contact radio, \u00e9teint son transpondeur, ou d\u00e9vie de sa trajectoire. C\u2019est ce qui s\u2019est pass\u00e9 pour les 4 avions du 11\/9, pourtant le NORAD, sous la direction d\u2019Eberhart, n\u2019a pas r\u00e9ussi \u00e0 en intercepter un seul.&nbsp;<a name=\"R_22\" href=\"#N_22\">[22]<\/a><\/li>\n<li>Sur les raisons de l\u2019\u00e9chec du NORAD \u00e0 les intercepter, celui-ci donna en 2001une premi\u00e8re version en disant que le NORAD avait eu connaissance des d\u00e9tournements et qu\u2019ils avaient essay\u00e9 d\u2019intercepter les avions, mais qu\u2019ils n\u2019\u00e9taient pas arriv\u00e9s \u00e0 temps.&nbsp;<a name=\"R_23\" href=\"#N_23\">[23]<\/a> Le NORAD maintint cette version de 2001 \u00e0 2004, mais dans le rapport de la Commission sur le 11\/9, il donna une version compl\u00e8tement diff\u00e9rente, selon laquelle&nbsp;: 1) la FAA n\u2019avait pas alert\u00e9 le NORAD au sujet du Vol American 11 avant qu\u2019il ne soit trop tard pour pouvoir l\u2019atteindre, et 2) la FAA n\u2019avait pas pr\u00e9venu le NORAD pour les trois autres vols avant que ces derniers ne s\u2019\u00e9crasent.&nbsp;<a name=\"R_24\" href=\"#N_24\">[24]<\/a><\/li>\n<li>Concernant le Vol American 77 (suppos\u00e9 avoir heurt\u00e9 le Pentagone), Eberhart et la Commission sur le 11\/9 ont d\u00e9clar\u00e9 que le \u201cNEADS n\u2019a jamais \u00e9t\u00e9 pr\u00e9venu que le vol AA&nbsp;77 avait \u00e9t\u00e9 d\u00e9tourn\u00e9.\u201d&nbsp;<a name=\"R_25\" href=\"#N_25\">[25]<\/a> Mais si cela est vrai, pourquoi alors Eberhart a-t-il d\u00e9clar\u00e9 devant le S\u00e9nat US environ six semaines apr\u00e8s les attentats que le NORAD avait fait d\u00e9coller des avions de chasse \u00e0 9 h 24 apr\u00e8s avoir appris que le Vol American 77 se dirigeait vers Washington, ajoutant qu\u2019il s\u2019agissait l\u00e0 d\u2019un avertissement \u00e9crit et document\u00e9&nbsp;?&nbsp;<a name=\"R_26\" href=\"#N_26\">[26]<\/a> La version de 2004 signifie-t-elle que les d\u00e9clarations d\u2019Eberhart en 2001 devant le S\u00e9nat \u00e9taient donc des mensonges&nbsp;? Ou bien cela veut-il dire que la FAA mentait lorsqu\u2019elle soulignait qu\u2019elle avait partag\u00e9 \u00ab&nbsp;les informations en temps r\u00e9el&nbsp;\u00bb avec le NORAD et le Pentagone au sujet de \u00ab&nbsp;tous les vols concern\u00e9s, y compris le Vol AA&nbsp;77&nbsp;\u00bb&nbsp;?&nbsp;<a name=\"R_27\" href=\"#N_27\">[27]<\/a><\/li>\n<li>Quant aux raisons possibles de l\u2019existence de cette nouvelle version&nbsp;: les chercheurs du Mouvement pour la v\u00e9rit\u00e9 sur le 11\/9 ont montr\u00e9 que la premi\u00e8re chronologie des \u00e9v\u00e9nements fournie par le NORAAD n\u2019exon\u00e9rait pas ce dernier, \u00e9tant donn\u00e9 qu\u2019il restait encore du temps pour intercepter les avions avant qu\u2019ils n\u2019aillent frapper le WTC et le Pentagone. Alors que la Commission pr\u00e9parait son rapport [en 2004], Eberhart a confirm\u00e9 que si le NEADS avait \u00e9t\u00e9 pr\u00e9venu des d\u00e9tournements comme l\u2019affirmait la FAA, ses gars auraient \u00e9t\u00e9 en mesure \u00ab&nbsp;d\u2019abattre les trois avions \u2013 [et m\u00eame] les quatre.&nbsp;\u00bb&nbsp;<a name=\"R_28\" href=\"#N_28\">[28]<\/a><\/li>\n<li>Interrog\u00e9 par la Commission sur le 11\/9 en mars 2004,&nbsp;<a name=\"R_29\" href=\"#N_29\">[29]<\/a> Eberhart a d\u00e9clar\u00e9 qu\u2019il \u00ab&nbsp;n\u2019avait pas connaissance des circonstances ayant entour\u00e9 les d\u00e9collages imm\u00e9diats (<i>scramble<\/i>) des avions&nbsp;\u00bb de chasse de Langley \u00e0 9 h 24. Il a expliqu\u00e9 n\u2019avoir appris que tr\u00e8s r\u00e9cemment que le NEADS avait fait d\u00e9coller ces chasseurs suite \u00e0 une fausse information&nbsp;<a name=\"R_30\" href=\"#N_30\">[30]<\/a> \u2013 selon laquelle le Vol AA&nbsp;11 \u00e9tait toujours en vol et se dirigeait vers Washington, alors qu\u2019en r\u00e9alit\u00e9 il venait de frapper la Tour Nord. Il parait impensable que le chef du NEADS ait ignor\u00e9 pendant plus de deux ans et demi les circonstances des d\u00e9collages imm\u00e9diats des chasseurs le 11 septembre 2001.<\/li>\n<li>Eberhart \u00e9tait en charge d\u2019\u00e9tablir le niveau d\u2019alerte INFOCON (<a href=\"https:\/\/en.wikipedia.org\/wiki\/Information_Operations_Condition\">Information Operations Condition<\/a>), qui permet de d\u00e9fendre les r\u00e9seaux de communication du Pentagone contre d\u2019\u00e9ventuelles attaques. \u00c0 peine 12 heures avant les attentats, INFOCON a \u00e9t\u00e9 ramen\u00e9 \u00e0 son plus faible niveau d\u2019alerte et n\u2019a \u00e9t\u00e9 relev\u00e9 qu\u2019apr\u00e8s la seconde frappe contre le Pentagone.&nbsp;<a name=\"R_31\" href=\"#N_31\">[31]<\/a><\/li>\n<li>Eberhart \u00e9tait aussi en charge de la plupart des exercices militaires du NORAD (les \u00ab&nbsp;<i>war games<\/i>&nbsp;\u00bb) en cours le 11\/9, comme Vigilant Guardian, lequel s\u2019articulait autour d\u2019un sc\u00e9nario o\u00f9 les terroristes d\u00e9tournaient un avion et le pr\u00e9cipitaient sur New York. L\u2019exercice \u00e9tait conduit en mode \u00ab&nbsp;<i>Sim over Live<\/i>&nbsp;\u00bb, ce qui signifie que les d\u00e9tournements simul\u00e9s \u00e9taient ins\u00e9r\u00e9s en direct dans le syst\u00e8me de contr\u00f4le du trafic a\u00e9rien. Le r\u00e9sultat fut que par moments, le personnel du NEADS ne savait plus si les \u00e9chos radars \u00e9taient vrais ou simul\u00e9s.<br \/>\nD\u2019apr\u00e8s le propre t\u00e9moignage d\u2019Eberhart, il n\u2019a r\u00e9alis\u00e9 qu\u2019apr\u00e8s la deuxi\u00e8me frappe contre le WTC, c\u2019est-\u00e0-dire apr\u00e8s 9 h 00, qu\u2019une \u00ab&nbsp;attaque terroriste coordonn\u00e9e&nbsp;\u00bb \u00e9tait en cours. Bien qu\u2019Eberhart fut le plus haut responsable en charge de la protection des \u00c9tats-Unis et du Canada contre des attaques terroristes, il a malgr\u00e9 tout laiss\u00e9 les \u00ab&nbsp;<i>war games<\/i>&nbsp;\u00bb se poursuivre jusqu\u2019apr\u00e8s 10 h du matin.<br \/>\nDe plus, le personnel du contr\u00f4le radar \u00e0 Cheyenne Mountain a demand\u00e9 au NEADS de \u00ab&nbsp;virer ces saloperies de simulations&nbsp;\u00bb. D\u2019apr\u00e8s l\u2019interview par la Commission sur le 11\/9 du G\u00e9n\u00e9ral de corps d\u2019arm\u00e9e canadien Rick Findley, qui \u00e9tait le directeur du personnel de combat du NORAD au CMOC le matin du 11-Septembre, il y eut, apr\u00e8s la 2e frappe contre le WTC, \u00ab&nbsp;une certaine confusion au sujet du nombre et de l\u2019identit\u00e9 des avions d\u00e9tourn\u00e9s.&nbsp;\u00bb&nbsp;<a name=\"R_32\" href=\"#N_32\">[32]<\/a> Pourtant, les simulations ont continu\u00e9 jusqu\u2019apr\u00e8s l\u2019attaque du Pentagone (\u00e0 9 h 37). Interrog\u00e9 sur les cons\u00e9quences des exercices militaires par la Commission sur le 11\/9, Eberhart a affirm\u00e9 de fa\u00e7on mensong\u00e8re qu\u2019elles \u00ab&nbsp;avaient cr\u00e9\u00e9 un retard d\u2019au plus 30 secondes.&nbsp;\u00bb&nbsp;<a name=\"R_33\" href=\"#N_33\">[33]<\/a><\/li>\n<li>Le chercheur et journaliste Michael Kane, de Global Free Press, qui a assist\u00e9 \u00e0 cette audition par la Commission sur le 11\/9, a d\u00e9clar\u00e9&nbsp;: \u00ab&nbsp;Apr\u00e8s le t\u00e9moignage sous serment du G\u00e9n\u00e9ral Eberhart, je lui ai demand\u00e9 qui \u00e9tait charg\u00e9 de coordonner les multiples \u2018war games\u2019 en cours le 11\/9. Il m\u2019a r\u00e9pondu&nbsp;: \u2018No comment\u2019&nbsp;\u00bb.&nbsp;<a name=\"R_34\" href=\"#N_34\">[34]<\/a> Pourtant, le Lieutenant-Colonel Dawne Deskins du secteur NEADS (North East Air Defense Sector) a expliqu\u00e9 \u00e0 la Commission que \u00ab&nbsp;les exercices qui se d\u00e9roulent au niveau du NORAD sont d\u00e9cid\u00e9s lors de conf\u00e9rences de programmation. Le planning des exercices du NORAD est d\u00e9cid\u00e9 principalement \u00e0 Peterson,&nbsp;\u00bb qui est sous la responsabilit\u00e9 du G\u00e9n\u00e9ral Eberhart.&nbsp;<a name=\"R_35\" href=\"#N_35\">[35]<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"c9hdr\">R\u00e9sum\u00e9 et conclusion<\/div>\n<div style=\"padding-left: 30px\">\nEberhart a fait plusieurs d\u00e9clarations qui sont clairement fausses et d\u2019autres tr\u00e8s peu plausibles, comme les faits suivants&nbsp;:<\/p>\n<ul style=\"padding-left: 30px\">\n<li>il a d\u00e9cid\u00e9 qu\u2019il valait mieux qu\u2019il se rende en voiture au Centre des Op\u00e9rations, car les choses \u00ab&nbsp;s\u2019\u00e9taient calm\u00e9es&nbsp;\u00bb ;<\/li>\n<li>les pilotes des avions du 11\/9 avaient d\u00e9clench\u00e9 leur code d\u2019alerte d\u00e9tournement (hijack code) ;<\/li>\n<li>il n\u2019a pas pu utiliser son t\u00e9l\u00e9phone portable pendant son trajet vers le CMOC ;<\/li>\n<li>les exercices militaires n\u2019ont pas retard\u00e9 la r\u00e9action du NEADS de plus de 30 secondes ;<\/li>\n<li>Il n\u2019a appris que r\u00e9cemment que les d\u00e9collages imm\u00e9diats des chasseurs \u00e0 9 h 24 \u00e9taient bas\u00e9s \u00e0 un faux rapport \u00e0 propos du Vol American 11.<\/li>\n<li>Il a appel\u00e9 le G\u00e9n\u00e9ral Myers alors que ce dernier \u00e9tait \u00e0 Capitole Hill ;<\/li>\n<\/ul>\n<p>Eberhart a \u00e9galement \u00e9t\u00e9 \u00e0 l\u2019origine de retards suite \u00e0 ses actions ou \u00e0 son absence d\u2019actions&nbsp;:<\/p>\n<ul style=\"padding-left: 30px\">\n<li>en abaissant INFOCON \u00e0 son plus bas niveau de protection ;<\/li>\n<li>en mettant 45 minutes ou plus \u00e0 se rendre en voiture au CMOC, \u00e9quip\u00e9 d\u2019un t\u00e9l\u00e9phone portable qui apparemment ne fonctionnait pas (ce qui signifie qu\u2019Eberhart, tout comme Bush, Cheney, Rumsfeld, Myers, Shelton et Winfield, est rest\u00e9 injoignable pendant toute la dur\u00e9e des attaques) ;<\/li>\n<li>en ordonnant aux pilotes de chasse de \u00ab&nbsp;regagner leur poste de combat,&nbsp;\u00bb c\u2019est-\u00e0-dire que ces derniers devaient attendre dans leurs avions tous moteurs \u00e9teints, et qu\u2019ils n\u2019\u00e9taient donc pas pr\u00eats \u00e0 d\u00e9coller imm\u00e9diatement ;<\/li>\n<li>en retardant le d\u00e9clenchement du plan SCATANA jusqu\u2019apr\u00e8s la fin des attaques ;<\/li>\n<li>en programment de multiples exercices militaires pour le jour du 11-Septembre, avec au moins l\u2019un deux en mode \u00ab&nbsp;Sim over Live&nbsp;\u00bb, et en ne donnant l\u2019ordre d\u2019arr\u00eater ces simulations d\u00e9routantes qu\u2019apr\u00e8s la frappe contre le Pentagone ;<\/li>\n<li>et enfin, en s\u2019alignant sur la d\u00e9claration de la Commission sur le 11\/9 selon laquelle la chronologie fournie par le NORAD en 2001 \u00e9tait fausse ; Eberhart reconnaissait ainsi que de deux choses l&rsquo;une&nbsp;: soit le NORAD avait menti en 2001, soit c&rsquo;est la Commission qui n\u2019avait pas dit la v\u00e9rit\u00e9 en 2004.<\/li>\n<\/ul>\n<p>Autrement dit, Eberhart n\u2019a accompli aucune action efficace en r\u00e9ponse aux d\u00e9tournements du 11\/9 \u2013 bien qu\u2019il ait \u00e9t\u00e9 pr\u00e9sent lors de la t\u00e9l\u00e9conf\u00e9rence militaire au moment o\u00f9 ces d\u00e9tournements \u00e9taient en cours -, sauf \u00e0 cr\u00e9er des retards dans la r\u00e9action des militaires.<br \/>\nDe nombreux \u00e9l\u00e9ments montrent qu\u2019Eberhart s\u2019est montr\u00e9 n\u00e9gligent par rapport \u00e0 son r\u00f4le et \u00e0 son devoir.&nbsp;<a name=\"R_36\" href=\"#N_36\">[36]<\/a><br \/>\nUne enqu\u00eate formelle doit \u00eatre diligent\u00e9e pour creuser plus avant et \u00e9tablir si une autre conclusion est possible.<\/p>\n<\/div>\n<p class=\"c9np\"><a href=\"https:\/\/www.consensus911.org\/fr\/point-mc-8-fr\/\">&lt;&lt; Point pr\u00e9c\u00e9dent<\/a>, <a href=\"https:\/\/www.consensus911.org\/fr\/point-mc-10-fr\/\">Point suivant &gt;&gt;<\/a><\/p>\n<div class=\"c9hdr\"><a name=\"REFS\"><\/a>R\u00e9f\u00e9rences du Point MC-9<\/div>\n<div class=\"c9refs\">\n<table class=\"ref_tbl\">\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_1\" href=\"#R_1\">[1]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nGerry J. Gilmore, \u201c<a href=\"http:\/\/web.archive.org\/web\/20140925102947\/http:\/\/www.defense.gov\/news\/newsarticle.aspx?id=44083\">Eberhart Tabbed to Head U.&nbsp;S. Northern Command<\/a>,\u201d Service de presse des Forces arm\u00e9es US, 8 mai 2002; Le Commandement pour l\u2019Am\u00e9rique du Nord (<i>Northern Command<\/i>, ou NORTHCOM) est consid\u00e9r\u00e9 comme \u201cla principale organisation militaire en charge de la d\u00e9fense de la nation\u201d; <i>NORAD and USNORTHCOM Public Affairs<\/i>, \u201c<i><a href=\"http:\/\/web.archive.org\/web\/20130118114658\/http:\/\/www.rcaf-arc.forces.gc.ca\/v2\/nr-sp\/index-eng.asp?id=13272\">NORAD and USNORTHCOM Honour 9\/11 Heroes<\/a><\/i>,\u201d 15 octobre 2012.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_2\" href=\"#R_2\">[2]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"https:\/\/9-11commission.gov\/report\/911Report.pdf\">Rapport de la Commission sur le 11\/9<\/a>, p.&nbsp;468, n. 228.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_3\" href=\"#R_3\">[3]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n\u201c<a href=\"http:\/\/web.archive.org\/web\/20130206215250\/http:\/\/media.nara.gov\/9-11\/MFR\/t-0148-911MFR-00788.pdf\"><i>Memorandum for the Record<\/i>&nbsp;: Interview du CINCNORAD (Haut commandement du NORAD), le g\u00e9n\u00e9ral Edward \u2018Ed\u2019 Eberhart<\/a>,\u201d Commission sur le 11\/9, 1er mars 2004.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_4\" href=\"#R_4\">[4]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nCommission sur le 11\/9, \u201c<a href=\"http:\/\/web.archive.org\/web\/20110224024217\/http:\/\/media.nara.gov\/9-11\/MFR\/t-0148-911MFR-00789.pdf\"><i>Memorandum for the Record&nbsp;:<\/i> Interview du Commandant-adjoint du NORAD, le g\u00e9n\u00e9ral de Corps d\u2019arm\u00e9e Rick Findley, des Forces canadiennes (CF)<\/a>,\u201d 1<sup>er<\/sup> mars 2004.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_5\" href=\"#R_5\">[5]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"http:\/\/web.archive.org\/web\/20110224024217\/http:\/\/media.nara.gov\/9-11\/MFR\/t-0148-911MFR-00789.pdf\">Ibid.<\/a>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_6\" href=\"#R_6\">[6]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"http:\/\/web.archive.org\/web\/20110224024217\/http:\/\/media.nara.gov\/9-11\/MFR\/t-0148-911MFR-00789.pdf\">Ibid.<\/a>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_7\" href=\"#R_7\">[7]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nLe g\u00e9n\u00e9ral Myers a confirm\u00e9 que peu apr\u00e8s l\u2019appel d\u2019Eberhart, le Pentagone avait \u00e9t\u00e9 frapp\u00e9 alors qu\u2019il y retournait. Source: <a href=\"https:\/\/govinfo.library.unt.edu\/911\/archive\/hearing12\/9-11Commission_Hearing_2004-06-17.pdf\">1er Comit\u00e9, 2e jour des 12 auditions publiques de la Commission nationale d\u2019enqu\u00eate sur les attentats terroristes contre les Etats-Unis, pr\u00e9sid\u00e9 par Thomas Kean<\/a>, 17 juin 2004.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_8\" href=\"#R_8\">[8]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nRichard Myers (et Malcolm McConnell), E<i>yes on the Horizon: Serving on the Front Lines of National Security<\/i> (New York: Editions Threshold, 2009), p.&nbsp;9.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_9\" href=\"#R_9\">[9]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n\u201c<a href=\"http:\/\/www.consensus911.org\/wp-content\/uploads\/2015\/11\/MFR_t-0148-911MFR-00751_cached.htm\"><i>Memorandum for the Record<\/i>&nbsp;: Interview de Richard Myers, Affiliated with NORAD, Commission sur le 11\/9<\/a>\u201d, 17 f\u00e9vrier 2004.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_10\" href=\"#R_10\">[10]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n\u201cRichard Myers, Interview par Jim Miklaszewski,\u201d <i>NBC News<\/i>, 11 septembre 2002; Myers, <i>Eyes on the Horizon<\/i>, p.&nbsp;9.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_11\" href=\"#R_11\">[11]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n\u201c<a href=\"http:\/\/web.archive.org\/web\/20130206215250\/http:\/\/media.nara.gov\/9-11\/MFR\/t-0148-911MFR-00788.pdf\"><i>Memorandum for the Record<\/i>&nbsp;: Interview du CINCNORAD<\/a>\u201d, 1er mars 2004.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_12\" href=\"#R_12\">[12]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"https:\/\/9-11commission.gov\/report\/911Report.pdf\">Rapport de la Commission sur le 11\/9<\/a>, p.&nbsp;465; T. R. Reid, \u201c<a href=\"https:\/\/web.archive.org\/web\/20080821094108\/http:\/\/www.washingtonpost.com\/wp-dyn\/content\/article\/2006\/07\/28\/AR2006072801617.html\"><i>Military to Idle NORAD Compound<\/i><\/a>\u201d, <i>Washington Post<\/i>, 29 juillet 2006.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_13\" href=\"#R_13\">[13]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nBruce Finley, \u201c<a href=\"https:\/\/www.denverpost.com\/2006\/07\/27\/military-to-put-cheyenne-mountain-on-standby\/\"><i>Military to Put Cheyenne Mountain on Standby<\/i><\/a>\u201d, <i>Denver Post<\/i>, 27 juillet 2006.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_14\" href=\"#R_14\">[14]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"https:\/\/9-11commission.gov\/report\/911Report.pdf\">Rapport de la Commission sur le 11\/9<\/a>, p.&nbsp;42; Pam Zubeck, \u201c<a href=\"https:\/\/gazette.com\/news\/cheyenne-mountain-s-fate-may-lie-in-study-contents\/article_de6472fe-8972-5c90-b511-1ab5136ee4c1.html\">Cheyenne Mountain\u2019s Fate May Lie in Study Contents<\/a>\u201d (<a href=\"http:\/\/www.consensus911.org\/wp-content\/uploads\/2021\/09\/CheyenneMountainsFateMayLieInStdyContents.zip\">backup<\/a>), <i>The Gazette<\/i>, 16 juin 2006; Lynn Spencer, <i>Touching History: The Untold Story of the Drama That Unfolded in the Skies Over America on 9\/11<\/i> (<i>New York: Free Press<\/i>, 2008), p.&nbsp;240.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_15\" href=\"#R_15\">[15]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"https:\/\/9-11commission.gov\/report\/911Report.pdf\">Rapport de la Commission sur le 11\/9<\/a>, pp. 38, 463.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_16\" href=\"#R_16\">[16]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nWilliam B. Scott, \u201c<a href=\"http:\/\/911research.wtc7.net\/cache\/planes\/defense\/aviationnow_jumpstart.htm\"><i>Exercise Jump-Starts Response to Attacks<\/i><\/a>,\u201d <i>Aviation Week &amp; Space Technology<\/i>, 3 juin 2002; Commission sur le 11\/9, 12e audition publique, 17 juin 2004; Spencer, <i>Touching History<\/i>, p.&nbsp;269.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_17\" href=\"#R_17\">[17]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"\/fr\/point-mc-6-fr\/\"><i>Point MC-6<\/i><\/a>&nbsp;: \u201cLes activit\u00e9s du G\u00e9n\u00e9ral Richard Myers pendant les attentats du 11-Septembre\u201d.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_18\" href=\"#R_18\">[18]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"\/fr\/point-flt-1-fr\/\"><i>Point Flt-1<\/i><\/a>&nbsp;: \u201cUne affirmation concernant les avions de ligne d\u00e9tourn\u00e9s\u201d.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_19\" href=\"#R_19\">[19]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n\u201cAucune explication n\u2019a \u00e9t\u00e9 fournie (ni m\u00eame demand\u00e9e) sur les raisons pour lesquelles Eberhart ne s\u2019est pas envol\u00e9 pour le CMOC depuis Peterson, en utilisant l\u2019h\u00e9liport de Cheyenne Mountain.\u201d Kevin Ryan, \u201c<a href=\"https:\/\/digwithin.net\/2013\/01\/12\/eberhart\/\">The Case Against Ralph Eberhart, NORAD\u2019s 9\/11 Commander<\/a>\u201d, 12 janvier 2013.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_20\" href=\"#R_20\">[20]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"https:\/\/9-11commission.gov\/report\/911Report.pdf\">Rapport de la Commission sur le 11\/9<\/a>, pp. 38, 463.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_21\" href=\"#R_21\">[21]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nLeslie Filson, A<i>ir War Over America: Sept. 11 Alters Face of Air Defense Mission<\/i> (Tyndall Air Force Base: 1st Air Force, 2003), p.&nbsp;55; Lynn Spencer, <i>Touching History<\/i>, p.&nbsp;27.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_22\" href=\"#R_22\">[22]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nBob Arnot, \u201c<i><a href=\"http:\/\/s3.amazonaws.com\/911timeline\/2001\/msnbc091201.html\">What Was Needed to Halt the Attacks? Cockpit Security, Quick Response Not in Evidence Tuesday<\/a><\/i>\u201d, MSNBC, 12 septembre 2001.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_23\" href=\"#R_23\">[23]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nNORAD, \u201c<a href=\"http:\/\/web.archive.org\/web\/20030809155434\/http:\/www.norad.mil\/index.cfm?fuseaction=home.news_rel_09_18_01\">NORAD&rsquo;S Response Times, Sept. 11, 2001<\/a>\u201d, 18 septembre, 2001.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_24\" href=\"#R_24\">[24]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"https:\/\/9-11commission.gov\/report\/911Report.pdf\">Ibid.<\/a>, pp. 18-30 (pdf-p. 35-37).\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_25\" href=\"#R_25\">[25]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"https:\/\/9-11commission.gov\/report\/911Report.pdf\">Ibid.<\/a>, p.&nbsp;34.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_26\" href=\"#R_26\">[26]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"http:\/\/web.archive.org\/web\/20020321022318\/http:\/\/www.public-action.com\/911\/eberhart-testimony.html\">Transcription de l\u2019audition devant le Comit\u00e9 des services de l\u2019Arm\u00e9e<\/a>, S\u00e9nat des \u00c9tats-Unis, 25 octobre 2001.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_27\" href=\"#R_27\">[27]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n\u201c<i>FAA Communications with NORAD on September 11, 2001: FAA clarification Memo to 9\/11 Independent Commission, 22 mai 2003<\/i>,\u201d publi\u00e9 par <a href=\"https:\/\/911truth.org\/\">911Truth.org<\/a>, 12 ao\u00fbt 2004.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_28\" href=\"#R_28\">[28]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"https:\/\/govinfo.library.unt.edu\/911\/archive\/hearing12\/9-11Commission_Hearing_2004-06-17.htm#two\">Commission sur le 11\/9, 12e audition publique<\/a>, 17 juin 2004.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_29\" href=\"#R_29\">[29]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n\u201c<a href=\"http:\/\/web.archive.org\/web\/20130206215250\/http:\/\/media.nara.gov\/9-11\/MFR\/t-0148-911MFR-00788.pdf\">Memorandum for the Record: Interview du CINCNORAD<\/a> (Commandant en chef du Norad), G\u00e9n\u00e9ral Edward \u2018Ed\u2019 Eberhart\u201d, Commission sur le 11\/9, 1<sup>er<\/sup> mars 2004.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_30\" href=\"#R_30\">[30]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"https:\/\/9-11commission.gov\/report\/911Report.pdf\">Rapport de la Commission sur le 11\/9<\/a>, pp. 26-27, 34; \u201c<a href=\"http:\/\/web.archive.org\/web\/20130206215250\/http:\/\/media.nara.gov\/9-11\/MFR\/t-0148-911MFR-00788.pdf\">Memorandum for the Record: Interview du CINCNORAD<\/a>\u201d, 1<sup>er<\/sup> mars 2004.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_31\" href=\"#R_31\">[31]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"https:\/\/web.archive.org\/web\/20100727210515\/https:\/\/www.scribd.com\/doc\/33866487\/T8-B8-Kara-Docs-3-Timelines-Fdr-1st-Fighter-Wing-History-Excerpt-Jul-Dec-01-w-Logs\">1st Fighter Wing History Excerpt<\/a>, juillet \u00e0 d\u00e9cembre 2001: p.&nbsp;61.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_32\" href=\"#R_32\">[32]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nCommission sur le 11\/9 \u201c<a href=\"http:\/\/web.archive.org\/web\/20110224024217\/http:\/\/media.nara.gov\/9-11\/MFR\/t-0148-911MFR-00789.pdf\">Memorandum for the Record, Interview du Commandant adjoint du NORAD, G?\u00e9n\u00e9ral de corps d\u2019arm\u00e9e Rick.Findley, Forces canadiennes (CF)<\/a>\u201d, 12 mars 2004.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_33\" href=\"#R_33\">[33]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"http:\/\/www.consensus911.org\/wp-content\/uploads\/2016\/09\/VigilantGuardian.htm\"> Vigilant Guardian 01-02 Planning Document<\/a>; \u201c<a href=\"http:\/\/shoestring911.blogspot.com\/2012_03_01_archive.html\">\u2019Real-World or Exercise\u2019: Did the U.&nbsp;S. Military Mistake the 9\/11 Attacks for a Training Scenario?<\/a>\u201d, \u201c<a href=\"https:\/\/www.reopen911.info\/News\/2012\/04\/13\/11-septembre-les-militaires-us-ont-ils-confondu-les-attentats-avec-un-exercice-dentrainement\/\">11-Septembre&nbsp;: les militaires US ont-ils confondu les attentats avec un exercice d\u2019entrainement&nbsp;?<\/a>\u201d (traduit en fran\u00e7ais par ReOpen911), Shoestring 911, 22 mars 2012; \u201c\u2018<a href=\"https:\/\/www.reopen911.info\/News\/2010\/08\/24\/pour-en-finir-avec-ces-satanees-simulations-les-radars-du-norad-affichaient-de-faux-traces-tout-au-long-des-attaques-du-11-septembre\/\">Pour en finir avec ces satan\u00e9es simulations\u2019&nbsp;: les radars du NORAD affichaient de faux trac\u00e9s tout au long des attaques du 11-Septembre<\/a>,\u201d (traduit en fran\u00e7ais par ReOpen911), Shoestring 911, 12 ao\u00fbt 2010; <a href=\"https:\/\/govinfo.library.unt.edu\/911\/archive\/hearing12\/9-11Commission_Hearing_2004-06-17.htm#two\">Commission sur le 11\/9, 12<sup>e<\/sup> audition publique<\/a>, 17 juin 2004. 9\/11 Consensus Panel, <a href=\"\/fr\/point-me-2-fr\/\"><i>Point ME-2<\/i><\/a>&nbsp;: \u201cL\u2019affirmation selon laquelle les exercices militaires n\u2019ont pas retard\u00e9 la riposte aux attentats du 11\/9\u201d.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_34\" href=\"#R_34\">[34]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nKane parle avec Eberhart apr\u00e8s la 12e audition publique de la Commission, 17 juin 2004. Source: Don Jacobs, \u201c<i><a href=\"http:\/\/web.archive.org\/web\/20070115024406\/http:\/\/www.physics911.net\/jacobs\">The Military Drills on 9-11: Bizarre Coincidence or Something Else?<\/a><\/i>\u201d par Paul Zarembka, ed., \u201c<i><a href=\"http:\/\/www.amazon.com\/Hidden-History-9-11\/dp\/158322825X\/\">The Hidden History of 9-11-2001<\/i><\/a>\u201d, Elsevier, 2006: p.&nbsp;129.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_35\" href=\"#R_35\">[35]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\n<a href=\"http:\/\/web.archive.org\/web\/20110224025153\/http:\/\/media.nara.gov\/9-11\/MFR\/t-0148-911MFR-00778.pdf\">La Commission sur le 11\/9, interview le Lt. Colonel Dawne Deskins<\/a>, du <i>North Eastern Air Defense Sector<\/i> (NEADS), visite sur place, 30 octobre 2003.\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"ref_nrs\">\n<div class=\"refnrs\"><a name=\"N_36\" href=\"#R_36\">[36]<\/a><\/div>\n<\/td>\n<td class=\"ref_txt\">\n<div class=\"rtxt-fr\">\nLe \u201cmanquement au devoir\u201d (<i>Dereliction of duty<\/i>) est un d\u00e9lit au titre du Code p\u00e9nal des \u00c9tats-Unis, Titre 10.892, article 92, et s\u2019applique \u00e0 toutes les branches de l\u2019arm\u00e9e US. Un membre du service des arm\u00e9es manque \u00e0 son devoir lorsqu\u2019il refuse d\u2019accomplir son devoir ou se met intentionnellement dans l\u2019incapacit\u00e9 de le faire (comme lorsque Eberhart a d\u00e9cid\u00e9 de se rendre en voiture \u00e0 Peterson). L\u2019article 92 s\u2019applique \u00e0 des membres du service des arm\u00e9es dont les actes ou les omissions atteignent le niveau de n\u00e9gligence criminelle (\u201c<a href=\"https:\/\/en.wikipedia.org\/wiki\/Dereliction_of_duty\"><i>Dereliction of Duty<\/i><\/a>\u201d, Wikipedia, acc\u00e9d\u00e9 en ao\u00fbt 2014).\n<\/div>\n<\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p><!-- c9refs -->\n<\/div>\n<p><!-- c9text --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Point MC-9&nbsp;: Les activit\u00e9s du G\u00e9n\u00e9ral Ralph Eberhart<br \/>Point MC-9&nbsp;: pendant les attentats du 11-Septembre <\/p>\n<p class=\"c9np\"><a href=\"https:\/\/www.consensus911.org\/fr\/point-mc-8-fr\/\">&lt;&lt; Point pr\u00e9c\u00e9dent<\/a>, <a href=\"https:\/\/www.consensus911.org\/fr\/point-mc-10-fr\/\">Point suivant &gt;&gt;<\/a><\/p>\n<p> <a name=\"INTRO\"><\/a>Introduction Le NORAD est l\u2019agence am\u00e9ricano-canadienne en charge de d\u00e9fendre l\u2019espace a\u00e9rien de l\u2019Am\u00e9rique du Nord. Ses proc\u00e9dures op\u00e9rationnelles standard \u2013 pour intercepter les avions lorsqu\u2019ils d\u00e9vient de leur trajectoire, [&#8230;]<\/p>\n","protected":false},"author":105,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8719","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.consensus911.org\/fr\/wp-json\/wp\/v2\/pages\/8719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consensus911.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.consensus911.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.consensus911.org\/fr\/wp-json\/wp\/v2\/users\/105"}],"replies":[{"embeddable":true,"href":"https:\/\/www.consensus911.org\/fr\/wp-json\/wp\/v2\/comments?post=8719"}],"version-history":[{"count":5,"href":"https:\/\/www.consensus911.org\/fr\/wp-json\/wp\/v2\/pages\/8719\/revisions"}],"predecessor-version":[{"id":21477,"href":"https:\/\/www.consensus911.org\/fr\/wp-json\/wp\/v2\/pages\/8719\/revisions\/21477"}],"wp:attachment":[{"href":"https:\/\/www.consensus911.org\/fr\/wp-json\/wp\/v2\/media?parent=8719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}